{"id":15135,"date":"2015-08-17T03:00:11","date_gmt":"2015-08-17T07:00:11","guid":{"rendered":"http:\/\/www.federated.ca\/?p=15135"},"modified":"2021-03-25T10:39:31","modified_gmt":"2021-03-25T14:39:31","slug":"protegez-votre-entreprise-contre-les-vols-commis-par-des-employes","status":"publish","type":"post","link":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/","title":{"rendered":"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s"},"content":{"rendered":"<p>Bien que les employeurs s\u2019efforcent toujours de trouver des employ\u00e9s mod\u00e8les, les choses ne se passent pas toujours comme pr\u00e9vu, et les nouveaux employ\u00e9s peuvent m\u00eame en venir \u00e0 commettre des vols dans l\u2019entreprise qui les a embauch\u00e9s. Le risque de vol commis par un employ\u00e9 peut cependant \u00eatre g\u00e9r\u00e9 gr\u00e2ce \u00e0 une strat\u00e9gie de pr\u00e9vention qui consiste \u00e0 \u00eatre s\u00e9lectif dans le processus d\u2019embauche et \u00e0 s\u2019assurer que les employ\u00e9s comprennent bien les cons\u00e9quences de leurs gestes.<\/p>\n<div class=\"call-to-action\"><a href=\"\/fr\/assurance-des-entreprises\/\">Trouvez la bonne solution d\u2019assurance pour votre entreprise.<\/a><\/div>\n<p>Les employ\u00e9s qui commettent des vols peuvent avoir un acc\u00e8s facile \u00e0 l\u2019argent ou \u00e0 la marchandise, estimer que leur salaire n\u2019est pas appropri\u00e9 ou bien \u00e9prouver des difficult\u00e9s financi\u00e8res. L\u2019\u00e9limination de l\u2019un ou l\u2019autre de ces facteurs, surtout l\u2019occasion (\u00e0 mesure que s\u2019accro\u00eet le risque de se faire prendre, la probabilit\u00e9 de vol d\u00e9cro\u00eet), contribuera \u00e0 r\u00e9duire les pertes.<\/p>\n<div class=\"related-story\">\n<p>Articles reli\u00e9s :<\/p>\n<ul>\n<li><a href=\"\/fr\/blog\/prevention-des-risques\/proteger-les-membres-de-votre-conseil-dadministration-grace-a-lassurance-des-administrateurs-et-des-dirigeants\/\">Prot\u00e9ger les membres de votre conseil d\u2019administration gr\u00e2ce \u00e0 l\u2019assurance des administrateurs et des dirigeants<\/a><\/li>\n<li><a href=\"\/fr\/blog\/prevention-des-risques\/assurez-la-securite-de-vos-employes-pendant-et-apres-votre-activite-estivale\/\">Assurez la s\u00e9curit\u00e9 de vos employ\u00e9s pendant et apr\u00e8s votre activit\u00e9 estivale<\/a><\/li>\n<\/ul>\n<\/div>\n<h3>Conseils d\u2019ordre g\u00e9n\u00e9ral<\/h3>\n<ul>\n<li>Mettez en place un programme de pr\u00e9s\u00e9lection des employ\u00e9s qui comprend la v\u00e9rification des r\u00e9f\u00e9rences fournies. Selon le poste \u00e0 pourvoir, la v\u00e9rification du casier judiciaire et de la solvabilit\u00e9 peut aussi \u00eatre souhaitable.<\/li>\n<li>R\u00e9digez des lignes directrices en mati\u00e8re de s\u00e9curit\u00e9 qui \u00e9noncent la politique d\u2019intervention de l\u2019entreprise en cas de vol commis par un employ\u00e9. Remettez un exemplaire des lignes directrices \u00e0 tous les employ\u00e9s et exigez qu\u2019ils signent un accus\u00e9 de r\u00e9ception confirmant qu\u2019ils les ont comprises.<\/li>\n<li>\u00c9laborez un programme de ressources humaines visant \u00e0 renforcer la loyaut\u00e9 des employ\u00e9s.<\/li>\n<li>Veillez \u00e0 ce que les marchandises et les biens de l\u2019entreprise ne soient pas faciles \u00e0 voler.<\/li>\n<\/ul>\n<h3>Conseils relatifs aux processus<\/h3>\n<ul>\n<li>\u00c9tablissez des proc\u00e9dures de contr\u00f4le relatives aux paiements \u00e0 partir de la petite caisse, aux d\u00e9p\u00f4ts bancaires, aux retraits, \u00e0 l\u2019\u00e9mission de ch\u00e8ques, \u00e0 la paie, aux rapprochements bancaires, ainsi qu\u2019au paiement de factures.<\/li>\n<li>Divisez les responsabilit\u00e9s et les fonctions de sorte qu\u2019aucun employ\u00e9 ne soit responsable de toutes les \u00e9tapes d\u2019une m\u00eame op\u00e9ration financi\u00e8re, et organisez les t\u00e2ches de mani\u00e8re \u00e0 ce que le travail de tout employ\u00e9 soit v\u00e9rifi\u00e9 par un autre employ\u00e9.<\/li>\n<li>Instaurez un programme de v\u00e9rifications r\u00e9guli\u00e8res et al\u00e9atoires des stocks.<\/li>\n<li>Surveillez les lieux au moyen d\u2019un syst\u00e8me de surveillance par t\u00e9l\u00e9vision en circuit ferm\u00e9 (TVCF). (Assurez-vous de garder en t\u00eate toute exigence l\u00e9gale en mati\u00e8re de protection de la vie priv\u00e9e.)<\/li>\n<li>V\u00e9rifiez que toutes les marchandises re\u00e7ues ou \u00e0 exp\u00e9dier correspondent aux factures ou aux documents d\u2019exp\u00e9dition.<\/li>\n<\/ul>\n<blockquote><p>L\u2019adoption de ces pratiques exemplaires est une bonne fa\u00e7on de d\u00e9courager le vol et de prot\u00e9ger vos profits.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Bien que les employeurs s\u2019efforcent toujours de trouver des employ\u00e9s mod\u00e8les, les choses ne se passent pas toujours comme pr\u00e9vu, et les nouveaux employ\u00e9s peuvent m\u00eame en venir \u00e0 commettre <a href=\"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":11,"featured_media":28741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[163],"tags":[],"class_list":["post-15135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petites-entreprises"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conseils pour pr\u00e9venir les vols commis par des employ\u00e9s<\/title>\n<meta name=\"description\" content=\"Article de blogue qui propose aux entreprises des moyens de r\u00e9duire le risque de vol commis par un employ\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Bien que les employeurs s\u2019efforcent toujours de trouver des employ\u00e9s mod\u00e8les, les choses ne se passent pas toujours comme pr\u00e9vu, et les nouveaux employ\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Federated, Compagnie d\u2019assurance du Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FedInsCanada\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-17T07:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-25T14:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federated Insurance\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federated Insurance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/\"},\"author\":{\"name\":\"Federated Insurance\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#\\\/schema\\\/person\\\/5fc35a52be2289516d44c241884c362a\"},\"headline\":\"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s\",\"datePublished\":\"2015-08-17T07:00:11+00:00\",\"dateModified\":\"2021-03-25T14:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/\"},\"wordCount\":534,\"publisher\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/employee-theft-1.jpg\",\"articleSection\":[\"Petites entreprises\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/\",\"url\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/\",\"name\":\"Conseils pour pr\u00e9venir les vols commis par des employ\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/employee-theft-1.jpg\",\"datePublished\":\"2015-08-17T07:00:11+00:00\",\"dateModified\":\"2021-03-25T14:39:31+00:00\",\"description\":\"Article de blogue qui propose aux entreprises des moyens de r\u00e9duire le risque de vol commis par un employ\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/employee-theft-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/employee-theft-1.jpg\",\"width\":800,\"height\":533,\"caption\":\"Photo d\u2019un employ\u00e9 volant de l\u2019argent \u00e0 son entreprise.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/blog\\\/petites-entreprises\\\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'acceuil\",\"item\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/\",\"name\":\"Federated Insurance Company of Canada\",\"description\":\"La s\u00e9curit\u00e9 de votre entreprise en t\u00eate\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#organization\",\"name\":\"Les assurances Federated\",\"url\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/FED_ENG_NOtag_shiftnav_210x52.png\",\"contentUrl\":\"https:\\\/\\\/www.federated.ca\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/FED_ENG_NOtag_shiftnav_210x52.png\",\"width\":210,\"height\":52,\"caption\":\"Les assurances Federated\"},\"image\":{\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FedInsCanada\\\/\",\"https:\\\/\\\/www.instagram.com\\\/federatedinsuranceca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/authwall?trk=ripf&amp;amp;amp;trkInfo=AQExgtg9_9rmAQAAAVx-tQL4XBOielaWooxEaw4kQGfXIqAVlPw7IbVWBdg-4ezDWDNXO2cp0GXtaWrXpPlk3S8ZhjlEcvoxf5Jti8CypWckNTc3e85aDADZtFHeDNEVc5LgQ80=&amp;amp;amp;originalReferer=http:\\\/\\\/avada.federated.ca\\\/business-insurance\\\/automotive-dealers-insurance\\\/&amp;amp;amp;sessionRedirect=https:\\\/\\\/www.linkedin.com\\\/company\\\/federated-insurance\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2TYZAr9C3puo4Tvg9Q151Q\"],\"description\":\"With Federated Insurance, you work directly with an industry expert who is committed to understanding the unique risks and opportunities associated with your business. With a dedicated agent and risk management team on your side, you will always get the right coverage for your company and can focus on what matters most. Trust. Advise. Protect.\",\"email\":\"info@federated.ca\",\"telephone\":\"1.844.628.6800\",\"legalName\":\"Federated Insurance\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.federated.ca\\\/fr\\\/#\\\/schema\\\/person\\\/5fc35a52be2289516d44c241884c362a\",\"name\":\"Federated Insurance\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conseils pour pr\u00e9venir les vols commis par des employ\u00e9s","description":"Article de blogue qui propose aux entreprises des moyens de r\u00e9duire le risque de vol commis par un employ\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/","og_locale":"fr_FR","og_type":"article","og_title":"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s","og_description":"Bien que les employeurs s\u2019efforcent toujours de trouver des employ\u00e9s mod\u00e8les, les choses ne se passent pas toujours comme pr\u00e9vu, et les nouveaux employ\u00e9s","og_url":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/","og_site_name":"La Federated, Compagnie d\u2019assurance du Canada","article_publisher":"https:\/\/www.facebook.com\/FedInsCanada\/","article_published_time":"2015-08-17T07:00:11+00:00","article_modified_time":"2021-03-25T14:39:31+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg","type":"image\/jpeg"}],"author":"Federated Insurance","twitter_misc":{"\u00c9crit par":"Federated Insurance","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#article","isPartOf":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/"},"author":{"name":"Federated Insurance","@id":"https:\/\/www.federated.ca\/fr\/#\/schema\/person\/5fc35a52be2289516d44c241884c362a"},"headline":"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s","datePublished":"2015-08-17T07:00:11+00:00","dateModified":"2021-03-25T14:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/"},"wordCount":534,"publisher":{"@id":"https:\/\/www.federated.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg","articleSection":["Petites entreprises"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/","url":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/","name":"Conseils pour pr\u00e9venir les vols commis par des employ\u00e9s","isPartOf":{"@id":"https:\/\/www.federated.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#primaryimage"},"image":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg","datePublished":"2015-08-17T07:00:11+00:00","dateModified":"2021-03-25T14:39:31+00:00","description":"Article de blogue qui propose aux entreprises des moyens de r\u00e9duire le risque de vol commis par un employ\u00e9","breadcrumb":{"@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#primaryimage","url":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg","contentUrl":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/08\/employee-theft-1.jpg","width":800,"height":533,"caption":"Photo d\u2019un employ\u00e9 volant de l\u2019argent \u00e0 son entreprise."},{"@type":"BreadcrumbList","@id":"https:\/\/www.federated.ca\/fr\/blog\/petites-entreprises\/protegez-votre-entreprise-contre-les-vols-commis-par-des-employes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'acceuil","item":"https:\/\/www.federated.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Prot\u00e9gez votre entreprise contre les vols commis par des employ\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.federated.ca\/fr\/#website","url":"https:\/\/www.federated.ca\/fr\/","name":"Federated Insurance Company of Canada","description":"La s\u00e9curit\u00e9 de votre entreprise en t\u00eate","publisher":{"@id":"https:\/\/www.federated.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.federated.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.federated.ca\/fr\/#organization","name":"Les assurances Federated","url":"https:\/\/www.federated.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.federated.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/03\/FED_ENG_NOtag_shiftnav_210x52.png","contentUrl":"https:\/\/www.federated.ca\/wp-content\/uploads\/2015\/03\/FED_ENG_NOtag_shiftnav_210x52.png","width":210,"height":52,"caption":"Les assurances Federated"},"image":{"@id":"https:\/\/www.federated.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FedInsCanada\/","https:\/\/www.instagram.com\/federatedinsuranceca\/","https:\/\/www.linkedin.com\/authwall?trk=ripf&amp;amp;amp;trkInfo=AQExgtg9_9rmAQAAAVx-tQL4XBOielaWooxEaw4kQGfXIqAVlPw7IbVWBdg-4ezDWDNXO2cp0GXtaWrXpPlk3S8ZhjlEcvoxf5Jti8CypWckNTc3e85aDADZtFHeDNEVc5LgQ80=&amp;amp;amp;originalReferer=http:\/\/avada.federated.ca\/business-insurance\/automotive-dealers-insurance\/&amp;amp;amp;sessionRedirect=https:\/\/www.linkedin.com\/company\/federated-insurance","https:\/\/www.youtube.com\/channel\/UC2TYZAr9C3puo4Tvg9Q151Q"],"description":"With Federated Insurance, you work directly with an industry expert who is committed to understanding the unique risks and opportunities associated with your business. With a dedicated agent and risk management team on your side, you will always get the right coverage for your company and can focus on what matters most. Trust. Advise. Protect.","email":"info@federated.ca","telephone":"1.844.628.6800","legalName":"Federated Insurance"},{"@type":"Person","@id":"https:\/\/www.federated.ca\/fr\/#\/schema\/person\/5fc35a52be2289516d44c241884c362a","name":"Federated Insurance"}]}},"_links":{"self":[{"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/posts\/15135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/comments?post=15135"}],"version-history":[{"count":0,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/posts\/15135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/media\/28741"}],"wp:attachment":[{"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/media?parent=15135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/categories?post=15135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federated.ca\/fr\/wp-json\/wp\/v2\/tags?post=15135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}